{"id":4492,"date":"2017-11-15T16:04:20","date_gmt":"2017-11-15T15:04:20","guid":{"rendered":"https:\/\/www.subsea-tech.com\/?page_id=4492"},"modified":"2026-03-12T11:58:56","modified_gmt":"2026-03-12T10:58:56","slug":"sciences-marines-recherche","status":"publish","type":"page","link":"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/","title":{"rendered":"Sciences marines \/ Recherche"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; background_image=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/12\/top_marinesciences.jpg&#8221; custom_padding=&#8221;240px||40px|&#8221; width_unit=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;off&#8221; custom_width_px=&#8221;1080px&#8221; custom_width_percent=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.18.0&#8243; text_font_size=&#8221;20px&#8221; background_layout=&#8221;dark&#8221; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; header_text_shadow_style=&#8221;preset5&#8243; text_line_height=&#8221;2.5em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Applications<\/p>\n<h1><strong>Sciences marines \/ Recherche<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#fcfcfc&#8221; transparent_background=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.27.5&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p data-start=\"624\" data-end=\"1010\">Subsea Tech accompagne depuis plusieurs ann\u00e9es des organismes scientifiques et des instituts de recherche dans leurs programmes d\u2019\u00e9tude et d\u2019exploration des milieux aquatiques. Les solutions robotis\u00e9es d\u00e9velopp\u00e9es par Subsea Tech permettent de r\u00e9aliser des missions d\u2019observation des \u00e9cosyst\u00e8mes marins, de monitoring environnemental, d\u2019hydrographie ou encore d\u2019arch\u00e9ologie sous-marine.<\/p>\n<p data-start=\"1012\" data-end=\"1321\">La modularit\u00e9 des syst\u00e8mes Subsea Tech permet d\u2019int\u00e9grer facilement diff\u00e9rents capteurs scientifiques afin de r\u00e9pondre aux besoins sp\u00e9cifiques des projets de recherche. Ces solutions peuvent \u00eatre utilis\u00e9es aussi bien pour des missions ponctuelles que pour des programmes de suivi environnemental \u00e0 long terme.<\/p>\n<p data-start=\"1323\" data-end=\"1616\">Les ROV et drones de surface Subsea Tech sont aujourd\u2019hui utilis\u00e9s par de nombreux organismes scientifiques et instituts de recherche \u00e0 travers le monde, parmi lesquels le DRASSM, le CNRS, l\u2019Office Fran\u00e7ais de la Biodiversit\u00e9, l\u2019Australian Antarctic Division ou encore le CIDCO au Canada.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.5&#8243; background_color=&#8221;#f4faff&#8221; custom_padding=&#8221;30px||30px||true|false&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset6&#8243; box_shadow_blur=&#8221;4px&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|50px||50px|false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 data-section-id=\"1smcvzd\" data-start=\"1639\" data-end=\"1664\">Applications typiques<\/h2>\n<p data-start=\"1649\" data-end=\"1762\">Les solutions Subsea Tech sont utilis\u00e9es dans le cadre de programmes scientifiques pour des missions telles que :<\/p>\n<ul data-start=\"1764\" data-end=\"1970\">\n<li data-section-id=\"2iqzl5\" data-start=\"1764\" data-end=\"1814\">\n<p data-start=\"1766\" data-end=\"1814\">observation et \u00e9tude d\u2019\u00e9cosyst\u00e8mes sous-marins<\/p>\n<\/li>\n<li data-section-id=\"jdlfl3\" data-start=\"1815\" data-end=\"1868\">\n<p data-start=\"1817\" data-end=\"1868\">monitoring environnemental des milieux aquatiques<\/p>\n<\/li>\n<li data-section-id=\"qbuxco\" data-start=\"1869\" data-end=\"1916\">\n<p data-start=\"1871\" data-end=\"1916\">campagnes hydrographiques et bathym\u00e9triques<\/p>\n<\/li>\n<li data-section-id=\"6zs4uv\" data-start=\"1917\" data-end=\"1970\">\n<p data-start=\"1919\" data-end=\"1970\">fouilles et prospection arch\u00e9ologique sous-marine<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px||0px|&#8221; top_divider_style=&#8221;asymmetric3&#8243; top_divider_color=&#8221;#3c3c3b&#8221; top_divider_height=&#8221;2px&#8221; top_divider_repeat=&#8221;1x&#8221; transparent_background=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.27.5&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/11\/marinesciences_ecosystemes.jpg&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_width=&#8221;1px&#8221; border_style=&#8221;solid&#8221; sticky=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#003366&#8243; header_2_font_size=&#8221;28px&#8221; header_2_line_height=&#8221;2.5em&#8221; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; header_3_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243;]<\/p>\n<h2>Observation des \u00e9cosyst\u00e8mes sous-marins<\/h2>\n<p data-start=\"2020\" data-end=\"2229\">Les ROV et cam\u00e9ras sous-marines Subsea Tech permettent de r\u00e9aliser des observations scientifiques et des enregistrements vid\u00e9o d\u2019\u00e9cosyst\u00e8mes aquatiques jusqu\u2019\u00e0 plusieurs centaines de m\u00e8tres de profondeur.<\/p>\n<p data-start=\"2231\" data-end=\"2388\">Ces syst\u00e8mes permettent d\u2019approcher et d\u2019\u00e9tudier des esp\u00e8ces marines craintives, dangereuses ou vivant \u00e0 des profondeurs difficilement accessibles \u00e0 l\u2019homme.<\/p>\n<h3 data-section-id=\"7td32f\" data-start=\"2390\" data-end=\"2414\">Exemples de missions<\/h3>\n<ul data-start=\"2416\" data-end=\"2633\">\n<li data-section-id=\"jqhxrc\" data-start=\"2416\" data-end=\"2471\">\n<p data-start=\"2418\" data-end=\"2471\">observation de la faune et de la flore sous-marines<\/p>\n<\/li>\n<li data-section-id=\"1exgtbj\" data-start=\"2472\" data-end=\"2520\">\n<p data-start=\"2474\" data-end=\"2520\">analyse comportementale d\u2019esp\u00e8ces aquatiques<\/p>\n<\/li>\n<li data-section-id=\"l2i21o\" data-start=\"2521\" data-end=\"2573\">\n<p data-start=\"2523\" data-end=\"2573\">r\u00e9alisation de vid\u00e9os scientifiques sous-marines<\/p>\n<\/li>\n<li data-section-id=\"1sp7dld\" data-start=\"2574\" data-end=\"2633\">\n<p data-start=\"2576\" data-end=\"2633\">pr\u00e9l\u00e8vement d\u2019\u00e9chantillons biologiques ou s\u00e9dimentaires<\/p>\n<\/li>\n<\/ul>\n<h3 data-section-id=\"1dal6og\" data-start=\"2635\" data-end=\"2648\">B\u00e9n\u00e9fices<\/h3>\n<ul data-start=\"2650\" data-end=\"2912\">\n<li data-section-id=\"1mqyyvp\" data-start=\"2650\" data-end=\"2713\">\n<p data-start=\"2652\" data-end=\"2713\">facilit\u00e9 de mise en \u0153uvre gr\u00e2ce \u00e0 la compacit\u00e9 des syst\u00e8mes<\/p>\n<\/li>\n<li data-section-id=\"ghvm96\" data-start=\"2714\" data-end=\"2795\">\n<p data-start=\"2716\" data-end=\"2795\">r\u00e9duction des risques et des co\u00fbts par rapport aux observations par plongeurs<\/p>\n<\/li>\n<li data-section-id=\"gtzk9o\" data-start=\"2796\" data-end=\"2849\">\n<p data-start=\"2798\" data-end=\"2849\">acc\u00e8s \u00e0 des zones profondes ou difficiles d\u2019acc\u00e8s<\/p>\n<\/li>\n<li data-section-id=\"m02e4r\" data-start=\"2850\" data-end=\"2912\">\n<p data-start=\"2852\" data-end=\"2912\">am\u00e9lioration de la connaissance des \u00e9cosyst\u00e8mes aquatiques<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px||0px|&#8221; top_divider_style=&#8221;asymmetric3&#8243; top_divider_color=&#8221;#3c3c3b&#8221; top_divider_height=&#8221;2px&#8221; top_divider_repeat=&#8221;1x&#8221; transparent_background=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row column_structure=&#8221;3_4,1_4&#8243; _builder_version=&#8221;4.27.5&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#003366&#8243; header_2_font_size=&#8221;28px&#8221; header_2_line_height=&#8221;2.5em&#8221; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; header_3_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243;]<\/p>\n<h2 data-section-id=\"1vf0mku\" data-start=\"3111\" data-end=\"3142\">Monitoring environnemental<\/h2>\n<p data-start=\"2949\" data-end=\"3112\">Les ROV et les drones de surface Subsea Tech peuvent embarquer diff\u00e9rents capteurs permettant de mesurer et de suivre de nombreux param\u00e8tres environnementaux.<\/p>\n<p data-start=\"3114\" data-end=\"3335\">Ces syst\u00e8mes sont r\u00e9guli\u00e8rement utilis\u00e9s par des autorit\u00e9s environnementales, des instituts scientifiques ou des soci\u00e9t\u00e9s d\u2019ing\u00e9nierie pour r\u00e9aliser des campagnes de suivi environnemental et d\u2019analyse du milieu aquatique.<\/p>\n<h3 data-section-id=\"7td32f\" data-start=\"3337\" data-end=\"3361\">Exemples de missions<\/h3>\n<ul data-start=\"3363\" data-end=\"3528\">\n<li data-section-id=\"1rtsbmd\" data-start=\"3363\" data-end=\"3399\">\n<p data-start=\"3365\" data-end=\"3399\">pr\u00e9l\u00e8vement d\u2019\u00e9chantillons d\u2019eau<\/p>\n<\/li>\n<li data-section-id=\"1k7spdd\" data-start=\"3400\" data-end=\"3428\">\n<p data-start=\"3402\" data-end=\"3428\">pr\u00e9l\u00e8vement de s\u00e9diments<\/p>\n<\/li>\n<li data-section-id=\"xcb31o\" data-start=\"3429\" data-end=\"3480\">\n<p data-start=\"3431\" data-end=\"3480\">mesure de param\u00e8tres physico-chimiques de l\u2019eau<\/p>\n<\/li>\n<li data-section-id=\"12kf56m\" data-start=\"3481\" data-end=\"3528\">\n<p data-start=\"3483\" data-end=\"3528\">cartographie th\u00e9matique du milieu aquatique<\/p>\n<\/li>\n<\/ul>\n<h3 data-section-id=\"1dal6og\" data-start=\"3530\" data-end=\"3543\">B\u00e9n\u00e9fices<\/h3>\n<ul data-start=\"3545\" data-end=\"3704\">\n<li data-section-id=\"qd7orj\" data-start=\"3545\" data-end=\"3595\">\n<p data-start=\"3547\" data-end=\"3595\">syst\u00e8mes compacts et facilement transportables<\/p>\n<\/li>\n<li data-section-id=\"12wbn8d\" data-start=\"3596\" data-end=\"3644\">\n<p data-start=\"3598\" data-end=\"3644\">r\u00e9duction des co\u00fbts de suivi environnemental<\/p>\n<\/li>\n<li data-section-id=\"fsc4ff\" data-start=\"3645\" data-end=\"3704\">\n<p data-start=\"3647\" data-end=\"3704\">automatisation et optimisation des protocoles de mesure<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/11\/marinesciences_monitoring.jpg&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_width=&#8221;1px&#8221; border_style=&#8221;solid&#8221; sticky=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px||0px|&#8221; top_divider_style=&#8221;asymmetric3&#8243; top_divider_color=&#8221;#3c3c3b&#8221; top_divider_height=&#8221;2px&#8221; top_divider_repeat=&#8221;1x&#8221; transparent_background=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.27.5&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/11\/marinesciences_hydrographic.jpg&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_width=&#8221;1px&#8221; border_style=&#8221;solid&#8221; sticky=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#003366&#8243; header_2_font_size=&#8221;28px&#8221; header_2_line_height=&#8221;2.5em&#8221; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; header_3_line_height=&#8221;1.5em&#8221;]<\/p>\n<h2>Hydrographie et arch\u00e9ologie sous-marine<\/h2>\n<p data-start=\"3754\" data-end=\"3976\">Les drones de surface Subsea Tech permettent de r\u00e9aliser des missions hydrographiques et de prospection sous-marine gr\u00e2ce \u00e0 l\u2019int\u00e9gration de capteurs tels que des sondeurs mono-faisceaux, multifaisceaux ou encore des ADCP.<\/p>\n<p data-start=\"3978\" data-end=\"4153\">Ces syst\u00e8mes peuvent \u00e9galement \u00eatre utilis\u00e9s dans le cadre de missions d\u2019arch\u00e9ologie sous-marine pour la d\u00e9tection, la localisation et la cartographie de sites arch\u00e9ologiques.<\/p>\n<p data-start=\"3978\" data-end=\"4153\">\n<h3 data-section-id=\"7td32f\" data-start=\"4155\" data-end=\"4179\">Exemples de missions<\/h3>\n<ul data-start=\"4181\" data-end=\"4396\">\n<li data-section-id=\"16ildjb\" data-start=\"4181\" data-end=\"4219\">\n<p data-start=\"4183\" data-end=\"4219\">bathym\u00e9trie mono ou multifaisceaux<\/p>\n<\/li>\n<li data-section-id=\"pexuay\" data-start=\"4220\" data-end=\"4250\">\n<p data-start=\"4222\" data-end=\"4250\">mesure des courants marins<\/p>\n<\/li>\n<li data-section-id=\"1219oz2\" data-start=\"4251\" data-end=\"4300\">\n<p data-start=\"4253\" data-end=\"4300\">d\u00e9tection de sites arch\u00e9ologiques sous-marins<\/p>\n<\/li>\n<li data-section-id=\"juegqf\" data-start=\"4301\" data-end=\"4348\">\n<p data-start=\"4303\" data-end=\"4348\">inspection visuelle de sites arch\u00e9ologiques<\/p>\n<\/li>\n<li data-section-id=\"1dgr5v8\" data-start=\"4349\" data-end=\"4396\">\n<p data-start=\"4351\" data-end=\"4396\">cartographie et g\u00e9olocalisation de vestiges<\/p>\n<\/li>\n<\/ul>\n<h3 data-section-id=\"1dal6og\" data-start=\"4398\" data-end=\"4411\">B\u00e9n\u00e9fices<\/h3>\n<ul data-start=\"4413\" data-end=\"4611\">\n<li data-section-id=\"t41amr\" data-start=\"4413\" data-end=\"4462\">\n<p data-start=\"4415\" data-end=\"4462\">acquisition de donn\u00e9es automatis\u00e9e et pr\u00e9cise<\/p>\n<\/li>\n<li data-section-id=\"wqfy6n\" data-start=\"4463\" data-end=\"4497\">\n<p data-start=\"4465\" data-end=\"4497\">bathym\u00e9trie \u00e0 haute r\u00e9solution<\/p>\n<\/li>\n<li data-section-id=\"1j14vjy\" data-start=\"4498\" data-end=\"4549\">\n<p data-start=\"4500\" data-end=\"4549\">r\u00e9duction des co\u00fbts des campagnes scientifiques<\/p>\n<\/li>\n<li data-section-id=\"12r2wje\" data-start=\"4550\" data-end=\"4611\">\n<p data-start=\"4552\" data-end=\"4611\">r\u00e9duction des risques li\u00e9s aux interventions de plongeurs<\/p>\n<\/li>\n<\/ul>\n<ul data-start=\"2146\" data-end=\"2237\"><\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f9f9f9&#8243; custom_padding=&#8221;40px|||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_2_font_size=&#8221;28px&#8221; custom_padding=&#8221;||10px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Produits recommand\u00e9s<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;|15px|15px|15px|false|true&#8221; link_option_url=&#8221;https:\/\/www.subsea-tech.com\/fr\/observer&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f9f9f9&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2023\/11\/Mini-ROV-Observer_SST-1.png&#8221; title_text=&#8221;Mini ROV Observer SST&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_3_font_size=&#8221;25px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3 style=\"text-align: center;\">Micro-ROV Observer<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\">ROV ultraportable id\u00e9al pour les missions d\u2019observation rapide et les campagnes scientifiques l\u00e9g\u00e8res.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;|15px|15px|15px|false|true&#8221; link_option_url=&#8221;https:\/\/www.subsea-tech.com\/fr\/mini-tortuga&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f9f9f9&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2023\/11\/Mini-TORTUGA.png&#8221; title_text=&#8221;Mini TORTUGA&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_3_font_size=&#8221;25px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3 style=\"text-align: center;\">Mini TORTUGA<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\">ROV polyvalent particuli\u00e8rement adapt\u00e9 aux missions scientifiques n\u00e9cessitant l\u2019int\u00e9gration de capteurs et d\u2019\u00e9quipements de mesure.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;|15px|15px|15px|false|true&#8221; link_option_url=&#8221;https:\/\/www.subsea-tech.com\/fr\/cat-surveyor&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f9f9f9&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2022\/09\/ST-PRODUIT-CAT-Surveyor-menu.png&#8221; title_text=&#8221;ST PRODUIT CAT Surveyor Menu&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_3_font_size=&#8221;25px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3 style=\"text-align: center;\">CAT-Surveyor<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\">Plateforme de surface d\u00e9di\u00e9e aux missions hydrographiques et bathym\u00e9triques ainsi qu\u2019\u00e0 l\u2019int\u00e9gration de capteurs oc\u00e9anographiques.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;|15px|15px|15px|false|true&#8221; link_option_url=&#8221;https:\/\/www.subsea-tech.com\/fr\/aircat&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f9f9f9&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2024\/12\/AirCAT_SST.png&#8221; title_text=&#8221;AirCAT_SST&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_3_font_size=&#8221;25px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3 style=\"text-align: center;\">AirCAT<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\">Drone de surface compact permettant l\u2019int\u00e9gration de diff\u00e9rents capteurs scientifiques pour des missions de monitoring environnemental ou d\u2019acquisition de donn\u00e9es.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#003366&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;10px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;38px&#8221; header_2_line_height=&#8221;2.5em&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Technologies embarqu\u00e9es<\/h2>\n<p style=\"text-align: center;\">Les solutions Subsea Tech peuvent int\u00e9grer une large gamme de capteurs scientifiques afin de r\u00e9pondre aux besoins des programmes de recherche.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px||50px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;25px&#8221; header_3_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3 data-section-id=\"1aay70s\" data-start=\"5432\" data-end=\"5473\" style=\"text-align: center;\">Cam\u00e9ras sous-marines haute d\u00e9finition<\/h3>\n<p data-start=\"5475\" data-end=\"5565\" style=\"text-align: center;\">Les cam\u00e9ras permettent l\u2019observation et l\u2019enregistrement vid\u00e9o des \u00e9cosyst\u00e8mes aquatiques.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2021\/11\/ST-ACC-Sonar-multifaisceaux-2D-Oculus.png&#8221; title_text=&#8221;ST ACC Sonar Multifaisceaux 2D Oculus&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;25px&#8221; header_3_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3 data-section-id=\"1l20qds\" data-start=\"5567\" data-end=\"5588\" style=\"text-align: center;\">Sonars d\u2019imagerie<\/h3>\n<p data-start=\"5590\" data-end=\"5710\" style=\"text-align: center;\">Les cam\u00e9ras acoustiques permettent d\u2019observer les structures ou les esp\u00e8ces m\u00eame en eau turbide ou en faible visibilit\u00e9.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2021\/11\/ST-ACC-Rosettes.png&#8221; title_text=&#8221;ST ACC Rosettes&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;25px&#8221; header_3_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3 data-section-id=\"pxcokj\" data-start=\"5712\" data-end=\"5741\" style=\"text-align: center;\">Capteurs environnementaux<\/h3>\n<p data-start=\"5743\" data-end=\"5858\" style=\"text-align: center;\">Les ROV et USV peuvent embarquer des sondes permettant de mesurer diff\u00e9rents param\u00e8tres physico-chimiques de l\u2019eau.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2021\/11\/ST-ACC-Norbit.png&#8221; title_text=&#8221;ST ACC Norbit&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;25px&#8221; header_3_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3 data-section-id=\"1dce189\" data-start=\"5860\" data-end=\"5895\" style=\"text-align: center;\">Sondeurs bathym\u00e9triques et ADCP<\/h3>\n<p data-start=\"5897\" data-end=\"6028\" style=\"text-align: center;\">Ces capteurs permettent de r\u00e9aliser des lev\u00e9s bathym\u00e9triques et des mesures de courants dans le cadre de campagnes hydrographiques.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|on||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;||||||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: center;\">Pour d\u00e9couvrir l\u2019ensemble des capteurs et \u00e9quipements disponibles, consultez nos pages :<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||30px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_button button_url=&#8221;https:\/\/www.subsea-tech.com\/fr\/accessoires-rov\/&#8221; button_text=&#8221;Accessoires ROV&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;22px&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_icon=&#8221;&#xf0a4;||fa||900&#8243; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_button button_url=&#8221;https:\/\/www.subsea-tech.com\/fr\/accessoires-usv&#8221; button_text=&#8221;Accessoires USV&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;22px&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_icon=&#8221;&#xf0a4;||fa||900&#8243; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Applications Sciences marines \/ RechercheSubsea Tech accompagne depuis plusieurs ann\u00e9es des organismes scientifiques et des instituts de recherche dans leurs programmes d\u2019\u00e9tude et d\u2019exploration des milieux aquatiques. Les solutions robotis\u00e9es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-4492","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subsea Tech - Sciences marines \/ Recherche<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subsea Tech - Sciences marines \/ Recherche\" \/>\n<meta property=\"og:description\" content=\"Applications Sciences marines \/ RechercheSubsea Tech accompagne depuis plusieurs ann\u00e9es des organismes scientifiques et des instituts de recherche dans leurs programmes d\u2019\u00e9tude et d\u2019exploration des milieux aquatiques. Les solutions robotis\u00e9es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/\" \/>\n<meta property=\"og:site_name\" content=\"Subsea Tech\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T10:58:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2023\/07\/ST-Image-Site.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SubseaTech_\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/sciences-marines-recherche\\\/\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/sciences-marines-recherche\\\/\",\"name\":\"Subsea Tech - Sciences marines \\\/ Recherche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#website\"},\"datePublished\":\"2017-11-15T15:04:20+00:00\",\"dateModified\":\"2026-03-12T10:58:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/sciences-marines-recherche\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/sciences-marines-recherche\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/sciences-marines-recherche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil | Home\",\"item\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Applications\",\"item\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/category\\\/applications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sciences marines \\\/ Recherche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#website\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/\",\"name\":\"Subsea Tech\",\"description\":\"Marine and Underwater Technologies\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.subsea-tech.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#organization\",\"name\":\"Subsea Tech\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Logo_Base_ST_2017.png\",\"contentUrl\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Logo_Base_ST_2017.png\",\"width\":648,\"height\":648,\"caption\":\"Subsea Tech\"},\"image\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SubseaTech_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/subsea-tech\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXTPqbfcCPWNnEgF4Ey7IHQ\",\"https:\\\/\\\/www.instagram.com\\\/subseatech\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subsea Tech - Sciences marines \/ Recherche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/","og_locale":"fr_FR","og_type":"article","og_title":"Subsea Tech - Sciences marines \/ Recherche","og_description":"Applications Sciences marines \/ RechercheSubsea Tech accompagne depuis plusieurs ann\u00e9es des organismes scientifiques et des instituts de recherche dans leurs programmes d\u2019\u00e9tude et d\u2019exploration des milieux aquatiques. Les solutions robotis\u00e9es [&hellip;]","og_url":"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/","og_site_name":"Subsea Tech","article_modified_time":"2026-03-12T10:58:56+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2023\/07\/ST-Image-Site.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SubseaTech_","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/","url":"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/","name":"Subsea Tech - Sciences marines \/ Recherche","isPartOf":{"@id":"https:\/\/www.subsea-tech.com\/#website"},"datePublished":"2017-11-15T15:04:20+00:00","dateModified":"2026-03-12T10:58:56+00:00","breadcrumb":{"@id":"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.subsea-tech.com\/fr\/sciences-marines-recherche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil | Home","item":"https:\/\/www.subsea-tech.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Applications","item":"https:\/\/www.subsea-tech.com\/fr\/category\/applications\/"},{"@type":"ListItem","position":3,"name":"Sciences marines \/ Recherche"}]},{"@type":"WebSite","@id":"https:\/\/www.subsea-tech.com\/#website","url":"https:\/\/www.subsea-tech.com\/","name":"Subsea Tech","description":"Marine and Underwater Technologies","publisher":{"@id":"https:\/\/www.subsea-tech.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.subsea-tech.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.subsea-tech.com\/#organization","name":"Subsea Tech","url":"https:\/\/www.subsea-tech.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.subsea-tech.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/12\/Logo_Base_ST_2017.png","contentUrl":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/12\/Logo_Base_ST_2017.png","width":648,"height":648,"caption":"Subsea Tech"},"image":{"@id":"https:\/\/www.subsea-tech.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SubseaTech_","https:\/\/www.linkedin.com\/company\/subsea-tech","https:\/\/www.youtube.com\/channel\/UCXTPqbfcCPWNnEgF4Ey7IHQ","https:\/\/www.instagram.com\/subseatech"]}]}},"_links":{"self":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/pages\/4492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=4492"}],"version-history":[{"count":2,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/pages\/4492\/revisions"}],"predecessor-version":[{"id":20155,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/pages\/4492\/revisions\/20155"}],"wp:attachment":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=4492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}