{"id":7653,"date":"2018-02-12T12:42:30","date_gmt":"2018-02-12T11:42:30","guid":{"rendered":"https:\/\/www.subsea-tech.com\/?p=7653"},"modified":"2018-03-22T15:04:30","modified_gmt":"2018-03-22T14:04:30","slug":"saclaf-systeme-acoustique-classification-automatique-fonds","status":"publish","type":"post","link":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/","title":{"rendered":"SACLAF &#8211; Syst\u00e8me Acoustique de CLassification Automatique des Fonds"},"content":{"rendered":"<p><span id=\"ember7712\" class=\"ember-view\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7734\" src=\"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/SACALF-SMF-343x250.png\" alt=\"\" width=\"469\" height=\"342\" \/><\/span><\/p>\n<p><span id=\"ember7712\" class=\"ember-view\">Subsea Tec<\/span><span id=\"ember7712\" class=\"ember-view\">h a d\u00e9velopp\u00e9, en partenariat avec la soci\u00e9t\u00e9 Seaviews, un syst\u00e8me acoustique de classification automatique des fonds (SACLAF) par echosondeur multifaisceaux. <\/span><\/p>\n<p><span id=\"ember7712\" class=\"ember-view\">C<\/span><span id=\"ember7712\" class=\"ember-view\">e<\/span><span id=\"ember7712\" class=\"ember-view\"> projet a \u00e9t\u00e9 men\u00e9 dans le cadre d&#8217;un Programme Investissement d&#8217;Avenir de l&#8217;ADEME (avec la contribution du P\u00f4le Mer M\u00e9diterran<\/span><span id=\"ember7712\" class=\"ember-view\">\u00e9e). le syst\u00e8me acoustique de classification automatique des fo<\/span><span id=\"ember7712\" class=\"ember-view\">nds permet de mesurer et de classer les variations du signal retour du sondeur afin de d\u00e9terminer la nature des fonds et d\u00e9tecter la pr\u00e9sence de v\u00e9g\u00e9tation marine (posidonie, zost\u00e8res, cy<\/span><span id=\"ember7712\" class=\"ember-view\">modoc\u00e9es), le <\/span><span id=\"ember7712\" class=\"ember-view\">but \u00e9tant de la discriminer finement des fonds s\u00e9dimentaires nus.<\/span><\/p>\n<p><span id=\"ember7712\" class=\"ember-view\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4066 alignleft\" src=\"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/11\/316-17-037-376x250.jpg\" alt=\"\" width=\"356\" height=\"237\" \/><\/span><span id=\"ember7712\" class=\"ember-view\">L&#8217;acqui<\/span><span id=\"ember7712\" class=\"ember-view\">sition <\/span><span id=\"ember7712\" class=\"ember-view\">des don<\/span><span id=\"ember7712\" class=\"ember-view\">n\u00e9es est r\u00e9alis\u00e9e au sondeur multifaisceaux <a href=\"https:\/\/www.subsea-tech.com\/seabed\/?lang=fr\">NORBIT WBMS<\/a>, d\u00e9ploy\u00e9 par notre drone de surface <a href=\"https:\/\/www.subsea-tech.com\/cat-surveyor\/?lang=fr\">CAT-Surveyor<\/a>. Le logiciel de navigation automatique du CAT-Surveyor permet de programmer le trajet du drone et d&#8217;automatiser l&#8217;acquisition. De plus, le faible tirant d&#8217;eau du CAT-Surveyor permet de r\u00e9aliser les acquisitions dans des zones de faible profondeur (80cm). La centrale inertielle install\u00e9e sur le CAT-Surveyor et la correction GPS RTK assur\u00e9e par l&#8217;antenne \u00e0 terre permettent de guider tr\u00e8s pr\u00e9cis\u00e9ment le drone et de r\u00e9aliser une bathym\u00e9trie 3D avec une pr\u00e9cision centim\u00e9trique. <\/span><\/p>\n<p><span id=\"ember7712\" class=\"ember-view\">L&#8217;acquisition permet d\u2019obtenir deux types de donn\u00e9es :<a id=\"ember7715\" class=\"feed-link ember-view\" href=\"mailto:st.sales@subsea-tech.com\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7657 alignright\" src=\"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/norbit1.jpg\" alt=\"\" width=\"229\" height=\"154\" \/><\/a><br \/>\n\u2022 les donn\u00e9es d\u2019\u00e9cho-int\u00e9gration (d\u00e9formation du signal retour en fonction de la nature des fonds).<br \/>\n\u2022 un indice de rugosit\u00e9 identifiant de fa\u00e7on tr\u00e8s pr\u00e9cise le relief du fond.<\/span><\/p>\n<p><span id=\"ember7712\" class=\"ember-view\">La <\/span><span id=\"ember7712\" class=\"ember-view\">technique mise en \u0153uvre permet la r\u00e9alisation de cartographies pr\u00e9cises et peu co\u00fbteuses sur de larges zones (\u00e9ventuellement en compl\u00e9ment d&#8217;images sonars et a\u00e9riennes). <\/span>En compl\u00e9ment peuvent \u00eatre associ\u00e9es des images sonars et a\u00e9riennes.<\/p>\n<p>T\u00e9l\u00e9charger la brochure du projet SACLAF ci-dessous.<img decoding=\"async\" src=\"https:\/\/www.subsea-tech.com\/wp-content\/plugins\/wp-file-download\/app\/admin\/assets\/images\/t.gif\" \/><\/p>\n\n<p><img decoding=\"async\" src=\"https:\/\/www.subsea-tech.com\/wp-content\/plugins\/wp-file-download\/app\/admin\/assets\/images\/t.gif\" \/><img decoding=\"async\" src=\"https:\/\/www.subsea-tech.com\/wp-content\/plugins\/wp-file-download\/app\/admin\/assets\/images\/t.gif\" \/><span id=\"ember7712\" class=\"ember-view\"><\/span><\/p>\n<p><span id=\"ember7712\" class=\"ember-view\">Pour plus d&#8217;information, contactez-nous : <\/span><a id=\"ember7715\" class=\"feed-link ember-view\" href=\"mailto:st.sales@subsea-tech.com\" target=\"_blank\" rel=\"noopener\">st.sales@subsea-tech.com<\/a><span id=\"ember7717\" class=\"ember-view\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Subsea Tech a d\u00e9velopp\u00e9 en partenariat avec la soci\u00e9t\u00e9 Seaviews un syst\u00e8me acoustique de classification automatique des fonds (SACLAF) par echosondeur multifaisceaux.<br \/>\nCe projet a \u00e9t\u00e9 men\u00e9 dans le cadre d&#8217;un Programme Investissement d&#8217;Avenir de l&#8217;ADEME (avec la contribution du P\u00f4le Mer M\u00e9diterran\u00e9e).<br \/>\nLe syst\u00e8me acoustique de classification automatique des fonds permet de mesurer et de classer les variations du signal retour du sondeur afin de d\u00e9terminer la nature des fonds et d\u00e9tecter la pr\u00e9sence de v\u00e9g\u00e9tation marine (posidonie, zost\u00e8res, cymodoc\u00e9es), le but \u00e9tant de la discriminer finement des fonds s\u00e9dimentaires nus.<br \/>\nLa technique mise en oeuvre permet la r\u00e9alisation de cartographies pr\u00e9cises et peu co\u00fbteuses sur de larges zones (\u00e9ventuellement en compl\u00e9ment d&#8217;images sonars et a\u00e9riennes).<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[31],"tags":[],"class_list":["post-7653","post","type-post","status-publish","format-standard","hentry","category-applications"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subsea Tech - SACLAF - Syst\u00e8me Acoustique de CLassification Automatique des Fonds<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subsea Tech - SACLAF - Syst\u00e8me Acoustique de CLassification Automatique des Fonds\" \/>\n<meta property=\"og:description\" content=\"Subsea Tech a d\u00e9velopp\u00e9 en partenariat avec la soci\u00e9t\u00e9 Seaviews un syst\u00e8me acoustique de classification automatique des fonds (SACLAF) par echosondeur multifaisceaux.  Ce projet a \u00e9t\u00e9 men\u00e9 dans le cadre d&#039;un Programme Investissement d&#039;Avenir de l&#039;ADEME (avec la contribution du P\u00f4le Mer M\u00e9diterran\u00e9e).  Le syst\u00e8me acoustique de classification automatique des fonds permet de mesurer et de classer les variations du signal retour du sondeur afin de d\u00e9terminer la nature des fonds et d\u00e9tecter la pr\u00e9sence de v\u00e9g\u00e9tation marine (posidonie, zost\u00e8res, cymodoc\u00e9es), le but \u00e9tant de la discriminer finement des fonds s\u00e9dimentaires nus. La technique mise en oeuvre permet la r\u00e9alisation de cartographies pr\u00e9cises et peu co\u00fbteuses sur de larges zones (\u00e9ventuellement en compl\u00e9ment d&#039;images sonars et a\u00e9riennes).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/\" \/>\n<meta property=\"og:site_name\" content=\"Subsea Tech\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-12T11:42:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-22T14:04:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/SACALF-SMF-343x250.png\" \/>\n<meta name=\"author\" content=\"Gr\u00e9gory MAURIN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SubseaTech_\" \/>\n<meta name=\"twitter:site\" content=\"@SubseaTech_\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/\"},\"author\":{\"name\":\"Gr\u00e9gory MAURIN\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#\\\/schema\\\/person\\\/602c100919a1dbda24bdb5f84e371710\"},\"headline\":\"SACLAF &#8211; Syst\u00e8me Acoustique de CLassification Automatique des Fonds\",\"datePublished\":\"2018-02-12T11:42:30+00:00\",\"dateModified\":\"2018-03-22T14:04:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/\"},\"wordCount\":335,\"publisher\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/SACALF-SMF-343x250.png\",\"articleSection\":[\"Applications\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/\",\"name\":\"Subsea Tech - SACLAF - Syst\u00e8me Acoustique de CLassification Automatique des Fonds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/SACALF-SMF-343x250.png\",\"datePublished\":\"2018-02-12T11:42:30+00:00\",\"dateModified\":\"2018-03-22T14:04:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/SACALF-SMF-343x250.png\",\"contentUrl\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/SACALF-SMF-343x250.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/saclaf-systeme-acoustique-classification-automatique-fonds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil | Home\",\"item\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Applications\",\"item\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/category\\\/applications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SACLAF &#8211; Syst\u00e8me Acoustique de CLassification Automatique des Fonds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#website\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/\",\"name\":\"Subsea Tech\",\"description\":\"Marine and Underwater Technologies\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.subsea-tech.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#organization\",\"name\":\"Subsea Tech\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Logo_Base_ST_2017.png\",\"contentUrl\":\"https:\\\/\\\/www.subsea-tech.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Logo_Base_ST_2017.png\",\"width\":648,\"height\":648,\"caption\":\"Subsea Tech\"},\"image\":{\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SubseaTech_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/subsea-tech\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXTPqbfcCPWNnEgF4Ey7IHQ\",\"https:\\\/\\\/www.instagram.com\\\/subseatech\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.subsea-tech.com\\\/#\\\/schema\\\/person\\\/602c100919a1dbda24bdb5f84e371710\",\"name\":\"Gr\u00e9gory MAURIN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd1009a42fea320fe5f052c14d38641fde9f1cacce83262541ed093f6f66c405?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd1009a42fea320fe5f052c14d38641fde9f1cacce83262541ed093f6f66c405?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd1009a42fea320fe5f052c14d38641fde9f1cacce83262541ed093f6f66c405?s=96&d=mm&r=g\",\"caption\":\"Gr\u00e9gory MAURIN\"},\"sameAs\":[\"https:\\\/\\\/www.subsea-tech.com\"],\"url\":\"https:\\\/\\\/www.subsea-tech.com\\\/fr\\\/author\\\/gma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subsea Tech - SACLAF - Syst\u00e8me Acoustique de CLassification Automatique des Fonds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/","og_locale":"fr_FR","og_type":"article","og_title":"Subsea Tech - SACLAF - Syst\u00e8me Acoustique de CLassification Automatique des Fonds","og_description":"Subsea Tech a d\u00e9velopp\u00e9 en partenariat avec la soci\u00e9t\u00e9 Seaviews un syst\u00e8me acoustique de classification automatique des fonds (SACLAF) par echosondeur multifaisceaux.  Ce projet a \u00e9t\u00e9 men\u00e9 dans le cadre d'un Programme Investissement d'Avenir de l'ADEME (avec la contribution du P\u00f4le Mer M\u00e9diterran\u00e9e).  Le syst\u00e8me acoustique de classification automatique des fonds permet de mesurer et de classer les variations du signal retour du sondeur afin de d\u00e9terminer la nature des fonds et d\u00e9tecter la pr\u00e9sence de v\u00e9g\u00e9tation marine (posidonie, zost\u00e8res, cymodoc\u00e9es), le but \u00e9tant de la discriminer finement des fonds s\u00e9dimentaires nus. La technique mise en oeuvre permet la r\u00e9alisation de cartographies pr\u00e9cises et peu co\u00fbteuses sur de larges zones (\u00e9ventuellement en compl\u00e9ment d'images sonars et a\u00e9riennes).","og_url":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/","og_site_name":"Subsea Tech","article_published_time":"2018-02-12T11:42:30+00:00","article_modified_time":"2018-03-22T14:04:30+00:00","og_image":[{"url":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/SACALF-SMF-343x250.png","type":"","width":"","height":""}],"author":"Gr\u00e9gory MAURIN","twitter_card":"summary_large_image","twitter_creator":"@SubseaTech_","twitter_site":"@SubseaTech_","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/#article","isPartOf":{"@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/"},"author":{"name":"Gr\u00e9gory MAURIN","@id":"https:\/\/www.subsea-tech.com\/#\/schema\/person\/602c100919a1dbda24bdb5f84e371710"},"headline":"SACLAF &#8211; Syst\u00e8me Acoustique de CLassification Automatique des Fonds","datePublished":"2018-02-12T11:42:30+00:00","dateModified":"2018-03-22T14:04:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/"},"wordCount":335,"publisher":{"@id":"https:\/\/www.subsea-tech.com\/#organization"},"image":{"@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/#primaryimage"},"thumbnailUrl":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/SACALF-SMF-343x250.png","articleSection":["Applications"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/","url":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/","name":"Subsea Tech - SACLAF - Syst\u00e8me Acoustique de CLassification Automatique des Fonds","isPartOf":{"@id":"https:\/\/www.subsea-tech.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/#primaryimage"},"image":{"@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/#primaryimage"},"thumbnailUrl":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/SACALF-SMF-343x250.png","datePublished":"2018-02-12T11:42:30+00:00","dateModified":"2018-03-22T14:04:30+00:00","breadcrumb":{"@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/#primaryimage","url":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/SACALF-SMF-343x250.png","contentUrl":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2018\/02\/SACALF-SMF-343x250.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.subsea-tech.com\/fr\/saclaf-systeme-acoustique-classification-automatique-fonds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil | Home","item":"https:\/\/www.subsea-tech.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Applications","item":"https:\/\/www.subsea-tech.com\/fr\/category\/applications\/"},{"@type":"ListItem","position":3,"name":"SACLAF &#8211; Syst\u00e8me Acoustique de CLassification Automatique des Fonds"}]},{"@type":"WebSite","@id":"https:\/\/www.subsea-tech.com\/#website","url":"https:\/\/www.subsea-tech.com\/","name":"Subsea Tech","description":"Marine and Underwater Technologies","publisher":{"@id":"https:\/\/www.subsea-tech.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.subsea-tech.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.subsea-tech.com\/#organization","name":"Subsea Tech","url":"https:\/\/www.subsea-tech.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.subsea-tech.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/12\/Logo_Base_ST_2017.png","contentUrl":"https:\/\/www.subsea-tech.com\/wp-content\/uploads\/2017\/12\/Logo_Base_ST_2017.png","width":648,"height":648,"caption":"Subsea Tech"},"image":{"@id":"https:\/\/www.subsea-tech.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SubseaTech_","https:\/\/www.linkedin.com\/company\/subsea-tech","https:\/\/www.youtube.com\/channel\/UCXTPqbfcCPWNnEgF4Ey7IHQ","https:\/\/www.instagram.com\/subseatech"]},{"@type":"Person","@id":"https:\/\/www.subsea-tech.com\/#\/schema\/person\/602c100919a1dbda24bdb5f84e371710","name":"Gr\u00e9gory MAURIN","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/dd1009a42fea320fe5f052c14d38641fde9f1cacce83262541ed093f6f66c405?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd1009a42fea320fe5f052c14d38641fde9f1cacce83262541ed093f6f66c405?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd1009a42fea320fe5f052c14d38641fde9f1cacce83262541ed093f6f66c405?s=96&d=mm&r=g","caption":"Gr\u00e9gory MAURIN"},"sameAs":["https:\/\/www.subsea-tech.com"],"url":"https:\/\/www.subsea-tech.com\/fr\/author\/gma\/"}]}},"_links":{"self":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/posts\/7653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=7653"}],"version-history":[{"count":0,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/posts\/7653\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=7653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=7653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.subsea-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=7653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}